{"id":196,"date":"2023-10-10T01:05:02","date_gmt":"2023-10-10T01:05:02","guid":{"rendered":"https:\/\/marcoslimma.com.br\/?p=196"},"modified":"2023-10-10T01:05:02","modified_gmt":"2023-10-10T01:05:02","slug":"arrastao-leva-multidao-as-ruas-declarando-apoio-ao-prefeito-dr-junior-que-se-emociona-no-lancamento-do-pamp","status":"publish","type":"post","link":"https:\/\/marcoslimma.com.br\/index.php\/2023\/10\/10\/arrastao-leva-multidao-as-ruas-declarando-apoio-ao-prefeito-dr-junior-que-se-emociona-no-lancamento-do-pamp\/","title":{"rendered":"Arrast\u00e3o leva multid\u00e3o \u00e0s ruas declarando apoio ao prefeito Dr. Junior que se emociona no lan\u00e7amento do (PAMP)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-200 size-large\" src=\"https:\/\/marcoslimma.com.br\/wp-content\/uploads\/2023\/10\/capa-1-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Peritor\u00f3 &#8211; O prefeito<strong> Dr. Junior (PP)<\/strong> tem apenas dois anos e alguns meses do seu primeiro mandato. Apesar do pouco tempo de governo, o prefeito peritoroense j\u00e1 \u00e9 avaliado como o melhor administrador da hist\u00f3ria do munic\u00edpio.<\/p>\n<p>E nesse s\u00e1bado realizou um dos maiores programas do estado do <strong>Maranh\u00e3o<\/strong> \u2013 <strong>Programa de Acelera\u00e7\u00e3o Municipal de Peritor\u00f3 (PAMP)<\/strong> \u2013 O evento foi sucesso absoluto. E o intuito \u00e9 trazer mais dignidade, gera\u00e7\u00e3o de emprego, e renda. Al\u00e9m de melhorar a vida dos mun\u00edcipes<\/p>\n<p>In\u00fameras pessoas de diversas localidades do munic\u00edpio foram prestigiar o evento que contou com a presen\u00e7a do prefeito de <strong>Trizidela do Vale<\/strong>, <strong>Deibson Bal\u00e9 (PDT<\/strong>), deputado estadual, <strong>Francisco Nagib (PSB)<\/strong>, vereadores, secret\u00e1rios, assessores e tantas outras pessoas<\/p>\n<p>Dr. Junior muito emocionado participou de toda o trajeto ao lado da sua esposa e filhos \u2013 No domingo ele gravou um v\u00eddeo em sua resid\u00eancia para agradecer tanta manifesta\u00e7\u00e3o de carinho \u201c<strong>Quero aqui agradecer, s\u00e1bado realmente voc\u00eas me emocionaram, voc\u00eas coroaram um trabalho, voc\u00eas entenderam esse espirito que colocamos em nossa gest\u00e3o para que Deus venha nos aben\u00e7oar e nos proteger&#8230; Quando voc\u00eas v\u00eam as ruas e dizem que n\u00f3s estamos trabalhando com essa nova pol\u00edtica, e querem a continuidade do trabalho, fico energizado e muito grato. Muito Obrigado Peritor\u00f3!\u201d<\/strong>, disse o gestor<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Multid\u00e3o declarando apoio ao prefeito Dr. Junior que se emociona no lan\u00e7amento do (PAMP)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/rL4KEPB8P7I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-197 size-full\" src=\"https:\/\/marcoslimma.com.br\/wp-content\/uploads\/2023\/10\/1696897843560044.jpg\" alt=\"\" width=\"924\" height=\"634\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-198 size-full\" src=\"https:\/\/marcoslimma.com.br\/wp-content\/uploads\/2023\/10\/169689804797448.jpg\" alt=\"\" width=\"826\" height=\"766\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-199 size-full\" src=\"https:\/\/marcoslimma.com.br\/wp-content\/uploads\/2023\/10\/1696898120373842.jpg\" alt=\"\" width=\"870\" height=\"700\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Peritor\u00f3 &#8211; O prefeito Dr. Junior (PP) tem apenas dois anos e alguns meses do seu primeiro mandato. Apesar do pouco tempo de governo, o prefeito peritoroense j\u00e1 \u00e9 avaliado&hellip;<\/p>\n","protected":false},"author":2,"featured_media":200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=196"}],"version-history":[{"count":0,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/posts\/196\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcoslimma.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}